{"id":850,"date":"2022-08-17T07:32:01","date_gmt":"2022-08-17T07:32:01","guid":{"rendered":"https:\/\/www.mayapalace.mx\/blog\/2022\/08\/17\/loteria-de-santander-resultados-del-sorteo-de-hoy-viernes-12-de-agosto\/"},"modified":"2022-08-17T07:32:01","modified_gmt":"2022-08-17T07:32:01","slug":"loteria-de-santander-resultados-del-sorteo-de-hoy-viernes-12-de-agosto","status":"publish","type":"post","link":"https:\/\/www.mayapalace.mx\/blog\/noticias\/loteria-de-santander-resultados-del-sorteo-de-hoy-viernes-12-de-agosto\/","title":{"rendered":"Loter\u00eda de Santander: resultados del sorteo de hoy viernes 12 de agosto"},"content":{"rendered":"<div id=\"contenedor\">\n<div>\n<section>\n<p itemprop=\"description\"><b>La <\/b><b>Loter&iacute;a de Santander<\/b><b> se jug&oacute; en <\/b><b>Colombia<\/b><b> durante la noche de este viernes 12 de agosto del 2022, desde las 11:00 p.m. (horario colombiano) y es transmitido por la se&ntilde;al de Canal TRO y Facebook Live. &iquest;Crees en la suerte y quieres dejar de contar monedas? Despreoc&uacute;pate y juega este sorteo, el cual es uno de los m&aacute;s populares y requeridos en el territorio colombiano.<\/b><\/p>\n<p itemprop=\"description\">Pese a su antig&uuml;edad, estas loter&iacute;as han sabido conservar el inter&eacute;s de los jugadores con el paso de los a&ntilde;os. Esto se debe a que los planes de premiaci&oacute;n son muy atractivos, y a que los billetes se adquieren por costos bajos, en comparaci&oacute;n a los de las compa&ntilde;&iacute;as competidoras. Por ello, esta loter&iacute;a ha ocupado una posici&oacute;n muy importante entre las actividades comerciales que benefician al pa&iacute;s.<\/p>\n<p itemprop=\"description\">Esta loter&iacute;a se juega todos los viernes y en caso de ser d&iacute;a festivo se aplaza para el siguiente d&iacute;a h&aacute;bil. En adici&oacute;n, tambi&eacute;n se conocieron los resultados de los principales chances que entregaron nuevos ganadores durante este d&iacute;a. Tenga en cuenta que para poder reclamar ese dinero debe presentar el billete de loter&iacute;a o de chance original y su documento de identificaci&oacute;n vigente.<\/p>\n<h2><b>Loter&iacute;a de Santander: resultado del viernes 12 de agosto<\/b><\/h2>\n<h2><b>&iquest;C&oacute;mo se gana la Loter&iacute;a de Santander?<\/b><\/h2>\n<p itemprop=\"description\">Por el acierto de las cuatro (4) cifras seleccionadas por el jugador, en cualquier orden, se pagar&aacute;n $208 por cada $1 apostado. 3. Por el acierto de las tres (3) cifras seleccionadas por el jugador, en su orden, se pagar&aacute;n $400 por cada $1 apostado.<\/p>\n<div data-hasads=\"0\" data-playerid=\"pHa2K63V\" id=\"Nn491iwi\">\n<p><img alt=\"La Loter&iacute;a de Santander se juega todos los viernes en Colombia. (Video: Loter&iacute;a de Santander)\" data-src=\"https:\/\/depor.com\/resizer\/AWdsCHQ1nHdwGMlhvk14izp9D-Y=\/580x326\/smart\/filters:format(jpeg):quality(75)\/cdn.jwplayer.com\/v2\/media\/Nn491iwi\/poster.jpg\" decoding=\"async\" id=\"image_Nn491iwi\" src=\"https:\/\/cdna.depor.com\/resources\/dist\/depor\/images\/default-md.png?d=2\" title=\"\"><\/p>\n<\/div><figcaption>La Loter&iacute;a de Santander se juega todos los viernes en Colombia. (Video: Loter&iacute;a de Santander) <\/figcaption><h2><b>Loter&iacute;a de Santander: resultado del viernes 5 de agosto<\/b><\/h2>\n<h2><b>&iquest;A qu&eacute; hora se juega la Loter&iacute;a de Santander?<\/b><\/h2>\n<p itemprop=\"description\">Como todas las semanas, la <b>Loter&iacute;a de Santander <\/b>est&aacute; programada para el viernes desde las 11:00 p.m. Podr&aacute;s ver la transmisi&oacute;n del sorteo EN VIVO y EN DIRECTO a trav&eacute;s del Canal TRO de Colombia y por el Facebook oficial de la Loter&iacute;a de Santander.<\/p>\n<h2><b>&iquest;Qu&eacute; hacer si eres uno de los ganadores de la Loter&iacute;a de Santander?<\/b><\/h2>\n<p itemprop=\"description\">Para solicitar la entrega del premio, se debe presentar el certificado de Registro &Uacute;nico Tributario (RUT) expedido por la DIAN y una copia de la c&eacute;dula de ciudadan&iacute;a. Un ganador de la loter&iacute;a no recibir&aacute; la suma de dinero completa debido a que la Direcci&oacute;n de Impuestos y Aduanas Nacionales (DIAN) le descontar&aacute; parte del monto.<\/p>\n<p itemprop=\"description\">Es as&iacute; como, de acuerdo con lo fijado en el Estatuto Tributario, el ganador tendr&aacute; que pagar el impuesto por ganancias ocasionales, que corresponde al 20 % del premio, m&aacute;s el descuento derivado del impuesto financiero conocido como 4 x 1.000 sobre el valor bruto obtenido.<\/p>\n<h2><mark><b>TE PUEDE INTERESAR<\/b><\/mark><\/h2>\n<h2><mark><b>VIDEO RECOMENDADO<\/b><\/mark><\/h2>\n<div data-hasads=\"0\" data-playerid=\"pHa2K63V\" id=\"Nn491iwi\">\n<p><img alt=\"La Loter&iacute;a de Santander se juega todos los viernes en Colombia. (Video: Loter&iacute;a de Santander)\" data-src=\"https:\/\/depor.com\/resizer\/AWdsCHQ1nHdwGMlhvk14izp9D-Y=\/580x326\/smart\/filters:format(jpeg):quality(75)\/cdn.jwplayer.com\/v2\/media\/Nn491iwi\/poster.jpg\" decoding=\"async\" id=\"image_Nn491iwi\" src=\"https:\/\/cdna.depor.com\/resources\/dist\/depor\/images\/default-md.png?d=2\" title=\"\"><\/p>\n<\/div><figcaption>La Loter&iacute;a de Santander se juega todos los viernes en Colombia. (Video: Loter&iacute;a de Santander) <\/figcaption><\/section>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/depor.com\/colombia\/local-co\/resultados-loteria-de-santander-en-vivo-ultimo-sorteo-del-viernes-12-de-agosto-numeros-ganadores-y-como-ver-el-juego-en-colombia-via-canal-tro-y-facebook-loterias-medellin-cali-santander-co-noticia\/\" class=\"button purchase\" rel=\"nofollow noopener\" target=\"_blank\">Lee mas<\/a><\/p>\n<p>Vas a encontrar tus  <a href=\"https:\/\/www.mayapalace.mx\/all-games\">juegos de maquinitas tragamonedas favoritos en Mayapalace casino gratis espa&ntilde;ol<\/a> conectados a unos acumulados espectaculares. Los mismos que has jugado en los casinos m&eacute;xico en linea. Puedes ver to compa&ntilde;eros ganar en tiempo real cuando van ganando los  acumulados.<\/p>\n<p>Los mejores  <a href=\"https:\/\/www.betzar.com\/all-games\" target=\"_blank\" rel=\"noopener\">juegos de Casino favoritos gratis espa&ntilde;ol<\/a> en Betzar y est&aacute;n conectadas a unos S&uacute;per Acumulados. Betzar es el sitio que mas r&aacute;pido paga a sus jugadores entre de todo los otros casinos en l&iacute;nea. Juega con confianza, aseg&uacute;rate que tus premios con Betzar.<\/p>\n<p>SpinBet cuenta con mas 100 <a href=\"https:\/\/www.spinbet.mx\/all-games\" target=\"_blank\" rel=\"noopener\">juegos de maquinitas, p&oacute;ker y juegos de mesa gratis espa&ntilde;ol<\/a>. SpinBet se esfuerza dar a sus jugadores los mejores juegos linkeados a unos super acumulados mas emocionante que podr&iacute;as encontrar en l&iacute;nea. Acumulados como Super Jackpot, Frutti Jackpot y las que mas pagan son de Legend Link. Mas gente que juegan mas se van acumulando los premios. En SpinBet puedes ver quien gana los acumulados en tiempo real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Loter\u00eda de Santander se jug\u00f3 en Colombia durante la noche de este viernes 12 de agosto del 2022, desde las 11:00 p.m. (horario colombiano) y es transmitido por la se\u00f1al de Canal TRO y Facebook Live. \u00bfCrees en la suerte y quieres dejar de contar monedas? Despreoc\u00fapate y juega este sorteo, el cual es&hellip;<\/p>\n","protected":false},"author":2,"featured_media":225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[88],"tags":[20,10,232,45,233,170,13],"_links":{"self":[{"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/posts\/850"}],"collection":[{"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":0,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/posts\/850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/media\/225"}],"wp:attachment":[{"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/media?parent=850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/categories?post=850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mayapalace.mx\/blog\/wp-json\/wp\/v2\/tags?post=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}